{"id":10282,"date":"2020-09-21T09:18:51","date_gmt":"2020-09-21T07:18:51","guid":{"rendered":"https:\/\/goerdeler.lspb.de\/wordpress\/?p=10282"},"modified":"2024-01-24T07:54:04","modified_gmt":"2024-01-24T06:54:04","slug":"ausgezeichnet-das-goerdeler-ist-eine-digitale-schule","status":"publish","type":"post","link":"https:\/\/goerdeler.lspb.de\/wordpress\/ausgezeichnet-das-goerdeler-ist-eine-digitale-schule\/","title":{"rendered":"Ausgezeichnet: Das Goerdeler ist eine \u201eDigitale Schule\u201c"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Anfang September&nbsp; wurde unser Gymnasium (als eine von 49 der 5500 Schulen in NRW) nach erfolgreicher Bewerbung&nbsp; als \u201eDigitale Schule\u201c ausgezeichnet. \u201eDie Corona-Krise hat im deutschen Bildungssystem f\u00fcr viel Sorge, aber auch f\u00fcr viel Bewegung gesorgt. Nach dem Motto \u201eTurning Desaster into Triumph\u201c haben die MINT-freundlichen Schulen ebenso wie die Digitalen Schulen \u2013 seit Jahren durch klare Arbeit vorbereitet \u2013 gezeigt, wie gute digitale Schule geht!\u201c \u00dcber diese W\u00fcrdigung des Vorsitzenden Thomas Sattelberger vom Verein \u201eMINT \u2013 Zukunft schaffen\u201c konnte sich unsere Schule bei der coronabedingt virtuell vorgenommen Ehrungsfeier &nbsp;f\u00fcr die \u201eDigitalen Schulen\u201c freuen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Martin Mevius, der als stellvertretender Schulleiter gemeinsam mit der Steuergruppe die Bewerbung der Schule initiierte, ist stolz auf die Gemeinschaftsleistung: \u201e Wir konnten mit unseren Konzepten, Handlungsweisen und unserer Ausstattung die Jury \u00fcberzeugen. In allen f\u00fcnf nachzuweisenden Kriterien wurden uns sehr gute Punktzahlen bescheinigt: P\u00e4dagogik und Lernkulturen, Qualifizierung der Lehrkr\u00e4fte, regionale Vernetzung, Konzept und Verstetigung sowie Technik und Ausstattung.\u201c<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Im Rahmen der Schulentwicklung wurde in den letzten Jahren die Unterrichtsentwicklung mit digitalen Medien, die Fortbildung der Lehrkr\u00e4fte, die Ausbildung der Sch\u00fcler zu Medienscouts und die Zusammenarbeit mit Institutionen und Firmen stetig intensiviert.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Auch dank der vom Schultr\u00e4ger und dem F\u00f6rderverein bereit gestellten Ausstattung gelingt das digitale Lernen und Kommunizieren bereits auf vielen Ebenen. Whiteboards und Beamer in jedem Unterrichtsraum, die \u201eLernstatt Paderborn\u201c als IT-Infrastruktur, neu ausgestattete Fachr\u00e4ume sowie mehrere mobile iPad-Koffer sind hierf\u00fcr nur einige Beispiele.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nachdem unser Gymnasium im Herbst 2019 bereits die Rezertifizierung als \u201eMINT-freundliche Schule\u201c erhielt, ist die aktuelle Auszeichnung f\u00fcr Schulleiterin Helga Lazar \u201enun ein weiterer Meilenstein auf dem Weg des aktuellen Bildungsauftrags. Das Signet ist uns ein Ansporn, unser digitales Feld gemeinsam weiter zu entwickeln.\u201c Ein mittelfristiges Ziel der Schule sei es, die 1:1 Ausstattung der Sch\u00fclerschaft mit digitalen Endger\u00e4ten zu realisieren.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"600\" src=\"https:\/\/goerdeler.lspb.de\/wordpress\/wp-content\/uploads\/2020-09-18_Goerdeler_DigitaleSchule_Urkunde.jpg\" alt=\"\" class=\"wp-image-10284\" srcset=\"https:\/\/goerdeler.lspb.de\/wordpress\/wp-content\/uploads\/2020-09-18_Goerdeler_DigitaleSchule_Urkunde.jpg 900w, https:\/\/goerdeler.lspb.de\/wordpress\/wp-content\/uploads\/2020-09-18_Goerdeler_DigitaleSchule_Urkunde-300x200.jpg 300w, https:\/\/goerdeler.lspb.de\/wordpress\/wp-content\/uploads\/2020-09-18_Goerdeler_DigitaleSchule_Urkunde-768x512.jpg 768w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/figure>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\"><em>Freude \u00fcber die Auszeichnung als Digitale Schule (v.l.n.r.): Martin Mevius (stellvertretender Schulleiter), Schulleiterin Helga Lazar, Sara Grabitz und Benjamin Buddensiek (beide Medienscouts, EF) Thomas Sch\u00f6nebeck (Schulverwaltungsassistent und IT-Verwaltung) und Silke Michels (Beauftragte f\u00fcr Medienp\u00e4dagogik).<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die Ehrung der \u201eDigitalen Schulen\u201c steht unter der Schirmherrschaft der Beauftragten der Bundesregierung f\u00fcr Digitalisierung, Staatsministerin Dorothee B\u00e4r. In der Schullandschaft in das Siegel rar ges\u00e4t: Nur 2,4 Prozent der Schulen in NRW sind als \u201cdigitale Schulen\u201d ausgezeichnet worden, bundesweit sind es 1,4 Prozent \u2013 also 450 von \u00fcber 32.000 Schulen. <strong><br><br><\/strong><em>Zur offiziellen Pressemitteilung der Initiative \u201eMINT Zukunft schaffen\u201c:<br><\/em><a href=\"https:\/\/mintzukunftschaffen.de\/2020\/09\/04\/auszeichnung-mint-freundliche-schulen-und-digitale-schulen-in-nordrhein-westfalen-2020\">https:\/\/mintzukunftschaffen.de\/2020\/09\/04\/auszeichnung-mint-freundliche-schulen-und-digitale-schulen-in-nordrhein-westfalen-2020<\/a><strong><\/strong><\/p>\n\n\n\n<p class=\"has-text-align-right wp-block-paragraph\"><em>Fotos: N. Lamberty-Freckmann<br>Text: MINT Zukunft schaffen \/ N. Lamberty-Freckmann<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Anfang September&nbsp; wurde unser Gymnasium (als eine von 49 der 5500 Schulen in NRW) nach erfolgreicher Bewerbung&nbsp; als \u201eDigitale Schule\u201c ausgezeichnet. \u201eDie Corona-Krise hat im deutschen Bildungssystem f\u00fcr viel Sorge, aber auch f\u00fcr viel Bewegung gesorgt. Nach dem Motto \u201eTurning Desaster into Triumph\u201c haben die MINT-freundlichen Schulen ebenso wie die Digitalen Schulen \u2013 seit Jahren [&hellip;]<\/p>\n","protected":false},"author":11,"featured_media":10283,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_themeisle_gutenberg_block_has_review":false,"footnotes":""},"categories":[140,1,193,180],"tags":[],"class_list":["post-10282","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aktuelles","category-allgemein","category-digitale_schule","category-mint"],"_links":{"self":[{"href":"https:\/\/goerdeler.lspb.de\/wordpress\/wp-json\/wp\/v2\/posts\/10282","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/goerdeler.lspb.de\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/goerdeler.lspb.de\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/goerdeler.lspb.de\/wordpress\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/goerdeler.lspb.de\/wordpress\/wp-json\/wp\/v2\/comments?post=10282"}],"version-history":[{"count":2,"href":"https:\/\/goerdeler.lspb.de\/wordpress\/wp-json\/wp\/v2\/posts\/10282\/revisions"}],"predecessor-version":[{"id":10286,"href":"https:\/\/goerdeler.lspb.de\/wordpress\/wp-json\/wp\/v2\/posts\/10282\/revisions\/10286"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/goerdeler.lspb.de\/wordpress\/wp-json\/wp\/v2\/media\/10283"}],"wp:attachment":[{"href":"https:\/\/goerdeler.lspb.de\/wordpress\/wp-json\/wp\/v2\/media?parent=10282"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/goerdeler.lspb.de\/wordpress\/wp-json\/wp\/v2\/categories?post=10282"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/goerdeler.lspb.de\/wordpress\/wp-json\/wp\/v2\/tags?post=10282"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}